{"id":194,"count":4,"description":"","link":"https:\/\/gear-boxes.xyz\/de\/application\/tag\/stepper-motor-gear-reducer\/","name":"stepper motor gear reducer","slug":"stepper-motor-gear-reducer","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/gear-boxes.xyz\/de\/wp-json\/wp\/v2\/tags\/194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gear-boxes.xyz\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/gear-boxes.xyz\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/gear-boxes.xyz\/de\/wp-json\/wp\/v2\/posts?tags=194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}