{"id":31,"count":1,"description":"","link":"https:\/\/gear-boxes.xyz\/es\/application\/tag\/digger-machine\/","name":"digger machine","slug":"digger-machine","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/gear-boxes.xyz\/es\/wp-json\/wp\/v2\/tags\/31","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gear-boxes.xyz\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/gear-boxes.xyz\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/gear-boxes.xyz\/es\/wp-json\/wp\/v2\/posts?tags=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}